{"id":105568,"date":"2026-02-13T11:38:54","date_gmt":"2026-02-13T04:38:54","guid":{"rendered":"https:\/\/www.doa.go.th\/th\/?p=105568"},"modified":"2026-02-16T11:41:27","modified_gmt":"2026-02-16T04:41:27","slug":"%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b8%98%e0%b8%b4%e0%b8%9a%e0%b8%94%e0%b8%b5%e0%b8%81%e0%b8%a3%e0%b8%a1%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%81-347","status":"publish","type":"post","link":"https:\/\/www.doa.go.th\/th\/news_board\/105568\/","title":{"rendered":"\u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e1a\u0e14\u0e35\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e38\u0e13\u0e18\u0e23\u0e23\u0e21 Integrity Pact \u0e02\u0e2d\u0e07\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e01\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e40\u0e07\u0e34\u0e19\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19 (\u0e2a\u0e15\u0e07)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 13 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e19\u0e32\u0e07\u0e28\u0e28\u0e34\u0e0d\u0e32 \u0e1b\u0e32\u0e19\u0e15\u0e31\u0e49\u0e19 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e1a\u0e14\u0e35\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e38\u0e13\u0e18\u0e23\u0e23\u0e21 Integrity Pact \u0e02\u0e2d\u0e07\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e01\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e40\u0e07\u0e34\u0e19\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19 (\u0e2a\u0e15\u0e07) \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e42\u0e25\u0e01 \u0e01\u0e2d\u0e07\u0e04\u0e25\u0e31\u0e07 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e19\u0e34\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e4d\u0e32\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e38\u0e13\u0e18\u0e23\u0e23\u0e21 \u0e42\u0e14\u0e22\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e20\u0e32\u0e04\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e32\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e16\u0e36\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e21\u0e2f \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 &#8220;\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e42\u0e25\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e1e.\u0e28. 2569&#8221; \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e42\u0e1b\u0e23\u0e48\u0e07\u0e43\u0e2a \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e44\u0e14\u0e49\u0e43\u0e19\u0e17\u0e38\u0e01\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1512\" height=\"1008\" data-id=\"105569\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/394.webp\" alt=\"\" class=\"wp-image-105569\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/394.webp 1512w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/394-300x200.webp 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/394-50x33.webp 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/394-768x512.webp 768w\" sizes=\"(max-width: 1512px) 100vw, 1512px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1455\" height=\"1040\" data-id=\"105570\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/395.webp\" alt=\"\" class=\"wp-image-105570\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/395.webp 1455w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/395-300x214.webp 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/395-50x36.webp 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/395-768x549.webp 768w\" sizes=\"(max-width: 1455px) 100vw, 1455px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1567\" height=\"1045\" data-id=\"105571\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/390.webp\" alt=\"\" class=\"wp-image-105571\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/390.webp 1567w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/390-300x200.webp 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/390-50x33.webp 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/390-768x512.webp 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/390-1536x1024.webp 1536w\" sizes=\"(max-width: 1567px) 100vw, 1567px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1477\" height=\"1108\" data-id=\"105572\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/391.webp\" alt=\"\" class=\"wp-image-105572\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/391.webp 1477w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/391-300x225.webp 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/391-50x38.webp 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/391-768x576.webp 768w\" sizes=\"(max-width: 1477px) 100vw, 1477px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1567\" height=\"1045\" data-id=\"105573\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/387.webp\" alt=\"\" class=\"wp-image-105573\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/387.webp 1567w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/387-300x200.webp 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/387-50x33.webp 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/387-768x512.webp 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/387-1536x1024.webp 1536w\" sizes=\"(max-width: 1567px) 100vw, 1567px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1521\" height=\"1014\" data-id=\"105574\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/389.webp\" alt=\"\" class=\"wp-image-105574\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/389.webp 1521w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/389-300x200.webp 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/389-50x33.webp 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/389-768x512.webp 768w\" sizes=\"(max-width: 1521px) 100vw, 1521px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1567\" height=\"1045\" data-id=\"105577\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/393.webp\" alt=\"\" class=\"wp-image-105577\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/393.webp 1567w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/393-300x200.webp 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/393-50x33.webp 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/393-768x512.webp 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/393-1536x1024.webp 1536w\" sizes=\"(max-width: 1567px) 100vw, 1567px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1567\" height=\"1045\" data-id=\"105575\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/392.webp\" alt=\"\" class=\"wp-image-105575\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/392.webp 1567w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/392-300x200.webp 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/392-50x33.webp 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/392-768x512.webp 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/392-1536x1024.webp 1536w\" sizes=\"(max-width: 1567px) 100vw, 1567px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1567\" height=\"1045\" data-id=\"105576\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/388.webp\" alt=\"\" class=\"wp-image-105576\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/388.webp 1567w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/388-300x200.webp 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/388-50x33.webp 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/388-768x512.webp 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/388-1536x1024.webp 1536w\" sizes=\"(max-width: 1567px) 100vw, 1567px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 13 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e19\u0e32\u0e07\u0e28\u0e28\u0e34\u0e0d\u0e32 \u0e1b\u0e32\u0e19\u0e15\u0e31\u0e49\u0e19 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e1a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":105570,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-105568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news_board"],"uagb_featured_image_src":{"full":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/395.webp",1455,1040,false],"thumbnail":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/395-50x36.webp",50,36,true],"medium":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/395-300x214.webp",300,214,true],"medium_large":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/395-768x549.webp",750,536,true],"large":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/395.webp",1455,1040,false],"1536x1536":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/395.webp",1455,1040,false],"2048x2048":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2026\/02\/395.webp",1455,1040,false]},"uagb_author_info":{"display_name":"\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23","author_link":"https:\/\/www.doa.go.th\/th\/author\/webmass\/"},"uagb_comment_info":0,"uagb_excerpt":"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 13 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e19\u0e32\u0e07\u0e28\u0e28\u0e34\u0e0d\u0e32 \u0e1b\u0e32\u0e19\u0e15\u0e31\u0e49\u0e19 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e1a&hellip;","acf":[],"_links":{"self":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts\/105568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/comments?post=105568"}],"version-history":[{"count":1,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts\/105568\/revisions"}],"predecessor-version":[{"id":105578,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts\/105568\/revisions\/105578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/media\/105570"}],"wp:attachment":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/media?parent=105568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/categories?post=105568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/tags?post=105568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}