{"id":77033,"date":"2024-07-01T17:57:56","date_gmt":"2024-07-01T10:57:56","guid":{"rendered":"https:\/\/www.doa.go.th\/th\/?p=77033"},"modified":"2024-07-02T07:46:04","modified_gmt":"2024-07-02T00:46:04","slug":"%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%95%e0%b9%89%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%8a%e0%b8%b5","status":"publish","type":"post","link":"https:\/\/www.doa.go.th\/th\/news_board\/77033\/","title":{"rendered":"\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e08\u0e32\u0e01\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e23\u0e31\u0e10\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e35\u0e19 (GACC)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2567 \u0e19\u0e32\u0e22\u0e23\u0e1e\u0e35\u0e20\u0e31\u0e17\u0e23\u0e4c \u0e08\u0e31\u0e19\u0e17\u0e23\u0e28\u0e23\u0e35\u0e27\u0e07\u0e28\u0e4c \u0e2d\u0e18\u0e34\u0e1a\u0e14\u0e35\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e2b\u0e49 \u0e14\u0e23.\u0e1e\u0e07\u0e28\u0e4c\u0e44\u0e17 \u0e44\u0e17\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e1a\u0e14\u0e35\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e08\u0e32\u0e01\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e23\u0e31\u0e10\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e35\u0e19 (GACC) \u0e08\u0e33\u0e19\u0e27\u0e19 3 \u0e23\u0e32\u0e22 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e40\u0e1e\u0e32\u0e30\u0e0a\u0e33\u0e15\u0e49\u0e19\u0e2a\u0e19\u0e43\u0e1a\u0e1e\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 &#8211; 4 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2567 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e31\u0e19\u0e15\u0e4c \u0e0a\u0e31\u0e49\u0e19 3 \u0e15\u0e36\u0e01\u0e08\u0e31\u0e01\u0e23\u0e17\u0e2d\u0e07 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e23\u0e31\u0e01\u0e02\u0e32\u0e1e\u0e37\u0e0a \u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e19\u0e32\u0e07\u0e0a\u0e48\u0e2d\u0e17\u0e34\u0e1e\u0e22\u0e4c \u0e28\u0e31\u0e25\u0e22\u0e1e\u0e07\u0e28\u0e4c \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e23\u0e31\u0e01\u0e02\u0e32\u0e1e\u0e37\u0e0a \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e23\u0e31\u0e01\u0e02\u0e32\u0e1e\u0e37\u0e0a \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e01\u0e2d\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e37\u0e0a \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e01\u0e2d\u0e07\u0e41\u0e1c\u0e19\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e14\u0e49\u0e27\u0e22<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77035\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449027123_883742180452492_4270289219746995753_n.jpg\" alt=\"\" class=\"wp-image-77035\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449027123_883742180452492_4270289219746995753_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449027123_883742180452492_4270289219746995753_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449027123_883742180452492_4270289219746995753_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449027123_883742180452492_4270289219746995753_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449027123_883742180452492_4270289219746995753_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77037\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449028292_883741237119253_8330646431208754895_n.jpg\" alt=\"\" class=\"wp-image-77037\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449028292_883741237119253_8330646431208754895_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449028292_883741237119253_8330646431208754895_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449028292_883741237119253_8330646431208754895_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449028292_883741237119253_8330646431208754895_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449028292_883741237119253_8330646431208754895_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77036\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449080078_883741287119248_538083333730879826_n.jpg\" alt=\"\" class=\"wp-image-77036\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449080078_883741287119248_538083333730879826_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449080078_883741287119248_538083333730879826_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449080078_883741287119248_538083333730879826_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449080078_883741287119248_538083333730879826_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449080078_883741287119248_538083333730879826_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77038\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449082518_883741303785913_850385329392128166_n.jpg\" alt=\"\" class=\"wp-image-77038\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449082518_883741303785913_850385329392128166_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449082518_883741303785913_850385329392128166_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449082518_883741303785913_850385329392128166_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449082518_883741303785913_850385329392128166_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449082518_883741303785913_850385329392128166_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77039\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449082525_883742157119161_1565639526607380644_n.jpg\" alt=\"\" class=\"wp-image-77039\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449082525_883742157119161_1565639526607380644_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449082525_883742157119161_1565639526607380644_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449082525_883742157119161_1565639526607380644_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449082525_883742157119161_1565639526607380644_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449082525_883742157119161_1565639526607380644_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"592\" height=\"395\" data-id=\"77034\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449100516_883739647119412_807638623061703451_n.jpg\" alt=\"\" class=\"wp-image-77034\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449100516_883739647119412_807638623061703451_n.jpg 592w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449100516_883739647119412_807638623061703451_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449100516_883739647119412_807638623061703451_n-50x33.jpg 50w\" sizes=\"(max-width: 592px) 100vw, 592px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77040\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449106591_883741410452569_3899636572929086098_n.jpg\" alt=\"\" class=\"wp-image-77040\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449106591_883741410452569_3899636572929086098_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449106591_883741410452569_3899636572929086098_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449106591_883741410452569_3899636572929086098_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449106591_883741410452569_3899636572929086098_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449106591_883741410452569_3899636572929086098_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77041\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449110351_883741183785925_1997360980372819118_n.jpg\" alt=\"\" class=\"wp-image-77041\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449110351_883741183785925_1997360980372819118_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449110351_883741183785925_1997360980372819118_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449110351_883741183785925_1997360980372819118_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449110351_883741183785925_1997360980372819118_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449110351_883741183785925_1997360980372819118_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77042\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449619391_883741360452574_1648546725372318274_n.jpg\" alt=\"\" class=\"wp-image-77042\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449619391_883741360452574_1648546725372318274_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449619391_883741360452574_1648546725372318274_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449619391_883741360452574_1648546725372318274_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449619391_883741360452574_1648546725372318274_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449619391_883741360452574_1648546725372318274_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77043\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449620650_883742103785833_2881195408466721313_n.jpg\" alt=\"\" class=\"wp-image-77043\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449620650_883742103785833_2881195408466721313_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449620650_883742103785833_2881195408466721313_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449620650_883742103785833_2881195408466721313_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449620650_883742103785833_2881195408466721313_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449620650_883742103785833_2881195408466721313_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77044\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449621850_883741150452595_5685114374555008568_n.jpg\" alt=\"\" class=\"wp-image-77044\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449621850_883741150452595_5685114374555008568_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449621850_883741150452595_5685114374555008568_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449621850_883741150452595_5685114374555008568_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449621850_883741150452595_5685114374555008568_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449621850_883741150452595_5685114374555008568_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77045\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449622795_883742207119156_1906456129403910346_n.jpg\" alt=\"\" class=\"wp-image-77045\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449622795_883742207119156_1906456129403910346_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449622795_883742207119156_1906456129403910346_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449622795_883742207119156_1906456129403910346_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449622795_883742207119156_1906456129403910346_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449622795_883742207119156_1906456129403910346_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77046\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449623688_883739650452745_1175916342758956802_n.jpg\" alt=\"\" class=\"wp-image-77046\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449623688_883739650452745_1175916342758956802_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449623688_883739650452745_1175916342758956802_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449623688_883739650452745_1175916342758956802_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449623688_883739650452745_1175916342758956802_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449623688_883739650452745_1175916342758956802_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77047\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449625687_883741263785917_1915872123937274702_n.jpg\" alt=\"\" class=\"wp-image-77047\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449625687_883741263785917_1915872123937274702_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449625687_883741263785917_1915872123937274702_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449625687_883741263785917_1915872123937274702_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449625687_883741263785917_1915872123937274702_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449625687_883741263785917_1915872123937274702_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77048\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449626550_883741193785924_7334774273685294131_n.jpg\" alt=\"\" class=\"wp-image-77048\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449626550_883741193785924_7334774273685294131_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449626550_883741193785924_7334774273685294131_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449626550_883741193785924_7334774273685294131_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449626550_883741193785924_7334774273685294131_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449626550_883741193785924_7334774273685294131_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77049\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449629173_883741453785898_5737925749951652778_n.jpg\" alt=\"\" class=\"wp-image-77049\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449629173_883741453785898_5737925749951652778_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449629173_883741453785898_5737925749951652778_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449629173_883741453785898_5737925749951652778_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449629173_883741453785898_5737925749951652778_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449629173_883741453785898_5737925749951652778_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77050\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630036_883741383785905_8230445212880907537_n.jpg\" alt=\"\" class=\"wp-image-77050\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630036_883741383785905_8230445212880907537_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630036_883741383785905_8230445212880907537_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630036_883741383785905_8230445212880907537_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630036_883741383785905_8230445212880907537_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630036_883741383785905_8230445212880907537_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77051\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630933_883742127119164_2533963974250034361_n.jpg\" alt=\"\" class=\"wp-image-77051\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630933_883742127119164_2533963974250034361_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630933_883742127119164_2533963974250034361_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630933_883742127119164_2533963974250034361_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630933_883742127119164_2533963974250034361_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630933_883742127119164_2533963974250034361_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77052\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630937_883741493785894_7404063114082197553_n.jpg\" alt=\"\" class=\"wp-image-77052\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630937_883741493785894_7404063114082197553_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630937_883741493785894_7404063114082197553_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630937_883741493785894_7404063114082197553_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630937_883741493785894_7404063114082197553_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449630937_883741493785894_7404063114082197553_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77055\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449631263_883741510452559_201529623115552496_n.jpg\" alt=\"\" class=\"wp-image-77055\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449631263_883741510452559_201529623115552496_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449631263_883741510452559_201529623115552496_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449631263_883741510452559_201529623115552496_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449631263_883741510452559_201529623115552496_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449631263_883741510452559_201529623115552496_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77053\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449631360_883741073785936_8414395604068162311_n.jpg\" alt=\"\" class=\"wp-image-77053\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449631360_883741073785936_8414395604068162311_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449631360_883741073785936_8414395604068162311_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449631360_883741073785936_8414395604068162311_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449631360_883741073785936_8414395604068162311_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449631360_883741073785936_8414395604068162311_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" data-id=\"77054\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449636226_883741473785896_889705138843515241_n.jpg\" alt=\"\" class=\"wp-image-77054\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449636226_883741473785896_889705138843515241_n.jpg 2048w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449636226_883741473785896_889705138843515241_n-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449636226_883741473785896_889705138843515241_n-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449636226_883741473785896_889705138843515241_n-768x512.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449636226_883741473785896_889705138843515241_n-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n<\/figure>\n\r\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2567 \u0e19\u0e32\u0e22\u0e23\u0e1e\u0e35\u0e20\u0e31\u0e17\u0e23\u0e4c \u0e08\u0e31\u0e19\u0e17\u0e23\u0e28\u0e23\u0e35\u0e27\u0e07\u0e28\u0e4c \u0e2d\u0e18\u0e34 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":77034,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-77033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news_board"],"uagb_featured_image_src":{"full":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449100516_883739647119412_807638623061703451_n.jpg",592,395,false],"thumbnail":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449100516_883739647119412_807638623061703451_n-50x33.jpg",50,33,true],"medium":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449100516_883739647119412_807638623061703451_n-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449100516_883739647119412_807638623061703451_n.jpg",592,395,false],"large":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449100516_883739647119412_807638623061703451_n.jpg",592,395,false],"1536x1536":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449100516_883739647119412_807638623061703451_n.jpg",592,395,false],"2048x2048":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/07\/449100516_883739647119412_807638623061703451_n.jpg",592,395,false]},"uagb_author_info":{"display_name":"\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23","author_link":"https:\/\/www.doa.go.th\/th\/author\/webmass\/"},"uagb_comment_info":0,"uagb_excerpt":"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2567 \u0e19\u0e32\u0e22\u0e23\u0e1e\u0e35\u0e20\u0e31\u0e17\u0e23\u0e4c \u0e08\u0e31\u0e19\u0e17\u0e23\u0e28\u0e23\u0e35\u0e27\u0e07\u0e28\u0e4c \u0e2d\u0e18\u0e34&hellip;","acf":[],"_links":{"self":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts\/77033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/comments?post=77033"}],"version-history":[{"count":2,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts\/77033\/revisions"}],"predecessor-version":[{"id":77084,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts\/77033\/revisions\/77084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/media\/77034"}],"wp:attachment":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/media?parent=77033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/categories?post=77033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/tags?post=77033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}