{"id":80540,"date":"2024-09-04T23:25:00","date_gmt":"2024-09-04T16:25:00","guid":{"rendered":"https:\/\/www.doa.go.th\/th\/?p=80540"},"modified":"2024-09-05T04:33:48","modified_gmt":"2024-09-04T21:33:48","slug":"%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1-76th-aiph-annual-congress-%e0%b8%82%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%a1%e0%b8%b2%e0%b8%84%e0%b8%a1%e0%b8%9e%e0%b8%b7","status":"publish","type":"post","link":"https:\/\/www.doa.go.th\/th\/news_board\/80540\/","title":{"rendered":"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 76th AIPH Annual Congress \u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 ( AIPH) \u0e13 \u0e01\u0e23\u0e38\u0e07\u0e27\u0e2d\u0e23\u0e4c\u0e0b\u0e2d \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e42\u0e1b\u0e41\u0e25\u0e19\u0e14\u0e4c"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 4 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2567 \u0e19\u0e32\u0e22\u0e23\u0e1e\u0e35\u0e20\u0e31\u0e17\u0e23\u0e4c \u0e08\u0e31\u0e19\u0e17\u0e23\u0e28\u0e23\u0e35\u0e27\u0e07\u0e28\u0e4c \u0e2d\u0e18\u0e34\u0e1a\u0e14\u0e35\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e2b\u0e49 \u0e14\u0e23.\u0e1e\u0e07\u0e28\u0e4c\u0e44\u0e17 \u0e44\u0e17\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e1a\u0e14\u0e35\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 76th AIPH Annual Congress \u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 ( AIPH) \u0e13 \u0e01\u0e23\u0e38\u0e07\u0e27\u0e2d\u0e23\u0e4c\u0e0b\u0e2d \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e42\u0e1b\u0e41\u0e25\u0e19\u0e14\u0e4c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e42\u0e25\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u0e1e.\u0e28. 2572 (\u0e23\u0e30\u0e14\u0e31\u0e1a A1) \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e42\u0e25\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e1e.\u0e28.2569 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e41\u0e25\u0e30\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e14\u0e49\u0e27\u0e22 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 (AIPH) \u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e0d AIPH General Meeting \u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 Mr. Leonardo Capitano \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e08\u0e32\u0e01\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e15\u0e32\u0e21\u0e27\u0e32\u0e23\u0e30\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e43\u0e19\u0e23\u0e2d\u0e1a\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e23\u0e48\u0e32\u0e07\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e1b\u0e35 \u0e1e.\u0e28. 2566-2569<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"960\" data-id=\"80543\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132301.jpg\" alt=\"\" class=\"wp-image-80543\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132301.jpg 1280w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132301-300x225.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132301-50x38.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132301-768x576.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1280\" height=\"960\" data-id=\"80545\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132305.jpg\" alt=\"\" class=\"wp-image-80545\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132305.jpg 1280w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132305-300x225.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132305-50x38.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132305-768x576.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"2560\" height=\"1920\" data-id=\"80546\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132300-scaled.jpg\" alt=\"\" class=\"wp-image-80546\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132300-scaled.jpg 2560w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132300-300x225.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132300-50x37.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132300-768x576.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132300-1536x1152.jpg 1536w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132300-2048x1536.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1012\" height=\"759\" data-id=\"80544\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132304.jpg\" alt=\"\" class=\"wp-image-80544\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132304.jpg 1012w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132304-300x225.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132304-50x38.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132304-768x576.jpg 768w\" sizes=\"(max-width: 1012px) 100vw, 1012px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" data-id=\"80548\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132306-scaled.jpg\" alt=\"\" class=\"wp-image-80548\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132306-scaled.jpg 2560w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132306-300x169.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132306-50x28.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132306-768x432.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132306-1536x864.jpg 1536w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132306-2048x1152.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"960\" data-id=\"80541\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132298.jpg\" alt=\"\" class=\"wp-image-80541\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132298.jpg 1280w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132298-300x225.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132298-50x38.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132298-768x576.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1239\" height=\"945\" data-id=\"80542\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132299.jpg\" alt=\"\" class=\"wp-image-80542\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132299.jpg 1239w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132299-300x229.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132299-50x38.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132299-768x586.jpg 768w\" sizes=\"(max-width: 1239px) 100vw, 1239px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1477\" height=\"1108\" data-id=\"80547\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132307.jpg\" alt=\"\" class=\"wp-image-80547\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132307.jpg 1477w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132307-300x225.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132307-50x38.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132307-768x576.jpg 768w\" sizes=\"(max-width: 1477px) 100vw, 1477px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1280\" data-id=\"80551\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132302.jpg\" alt=\"\" class=\"wp-image-80551\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132302.jpg 960w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132302-225x300.jpg 225w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132302-38x50.jpg 38w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132302-768x1024.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"794\" height=\"993\" data-id=\"80550\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132303.jpg\" alt=\"\" class=\"wp-image-80550\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132303.jpg 794w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132303-240x300.jpg 240w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132303-40x50.jpg 40w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132303-768x960.jpg 768w\" sizes=\"(max-width: 794px) 100vw, 794px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"972\" height=\"1685\" data-id=\"80549\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132308.jpg\" alt=\"\" class=\"wp-image-80549\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132308.jpg 972w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132308-173x300.jpg 173w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132308-29x50.jpg 29w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132308-768x1331.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132308-886x1536.jpg 886w\" sizes=\"(max-width: 972px) 100vw, 972px\" \/><\/figure>\n<\/figure>\n\r\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 4 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2567 \u0e19\u0e32\u0e22\u0e23\u0e1e\u0e35\u0e20\u0e31\u0e17\u0e23\u0e4c \u0e08\u0e31\u0e19\u0e17\u0e23\u0e28\u0e23\u0e35\u0e27\u0e07\u0e28\u0e4c \u0e2d\u0e18\u0e34 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":80547,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-80540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news_board"],"uagb_featured_image_src":{"full":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132307.jpg",1477,1108,false],"thumbnail":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132307-50x38.jpg",50,38,true],"medium":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132307-300x225.jpg",300,225,true],"medium_large":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132307-768x576.jpg",750,563,true],"large":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132307.jpg",1477,1108,false],"1536x1536":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132307.jpg",1477,1108,false],"2048x2048":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1132307.jpg",1477,1108,false]},"uagb_author_info":{"display_name":"\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23","author_link":"https:\/\/www.doa.go.th\/th\/author\/webmass\/"},"uagb_comment_info":0,"uagb_excerpt":"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 4 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2567 \u0e19\u0e32\u0e22\u0e23\u0e1e\u0e35\u0e20\u0e31\u0e17\u0e23\u0e4c \u0e08\u0e31\u0e19\u0e17\u0e23\u0e28\u0e23\u0e35\u0e27\u0e07\u0e28\u0e4c \u0e2d\u0e18\u0e34&hellip;","acf":[],"_links":{"self":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts\/80540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/comments?post=80540"}],"version-history":[{"count":4,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts\/80540\/revisions"}],"predecessor-version":[{"id":80555,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts\/80540\/revisions\/80555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/media\/80547"}],"wp:attachment":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/media?parent=80540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/categories?post=80540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/tags?post=80540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}