{"id":80797,"date":"2024-09-11T14:59:04","date_gmt":"2024-09-11T07:59:04","guid":{"rendered":"https:\/\/www.doa.go.th\/th\/?p=80797"},"modified":"2024-09-11T14:59:06","modified_gmt":"2024-09-11T07:59:06","slug":"%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b9%80%e0%b8%87%e0%b8%b4%e0%b8%99%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%ab%e0%b8%a1%e0%b8%b8%e0%b8%99%e0%b9%80%e0%b8%a7","status":"publish","type":"post","link":"https:\/\/www.doa.go.th\/th\/news_board\/80797\/","title":{"rendered":"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e07\u0e34\u0e19\u0e17\u0e38\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e23\u0e42\u0e0b\u0e40\u0e1a\u0e35\u0e22\u0e21 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 4\/2567"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 11 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2567 \u0e14\u0e23.\u0e20\u0e31\u0e2a\u0e0a\u0e0d\u0e20\u0e13 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e41\u0e08\u0e49\u0e07 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e1a\u0e14\u0e35\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e07\u0e34\u0e19\u0e17\u0e38\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e23\u0e42\u0e0b\u0e40\u0e1a\u0e35\u0e22\u0e21 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 4\/2567 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e19\u0e32\u0e07\u0e08\u0e34\u0e23\u0e32\u0e1e\u0e23\u0e23\u0e13 \u0e17\u0e2d\u0e07\u0e2b\u0e22\u0e2d\u0e14 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e01\u0e2d\u0e07\u0e27\u0e34\u0e08\u0e31\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e17\u0e38\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e23\u0e42\u0e0b\u0e40\u0e1a\u0e35\u0e22\u0e21\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e40\u0e25\u0e47\u0e01 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e08\u0e32\u0e01\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 Zoom Cloud Meetings<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1473\" height=\"1112\" data-id=\"80798\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019178.jpg\" alt=\"\" class=\"wp-image-80798\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019178.jpg 1473w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019178-300x226.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019178-50x38.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019178-768x580.jpg 768w\" sizes=\"(max-width: 1473px) 100vw, 1473px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1528\" height=\"1071\" data-id=\"80799\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019181.jpg\" alt=\"\" class=\"wp-image-80799\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019181.jpg 1528w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019181-300x210.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019181-50x35.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019181-768x538.jpg 768w\" sizes=\"(max-width: 1528px) 100vw, 1528px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1572\" height=\"1041\" data-id=\"80800\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019182.jpg\" alt=\"\" class=\"wp-image-80800\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019182.jpg 1572w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019182-300x199.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019182-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019182-768x509.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019182-1536x1017.jpg 1536w\" sizes=\"(max-width: 1572px) 100vw, 1572px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1572\" height=\"1041\" data-id=\"80801\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019179.jpg\" alt=\"\" class=\"wp-image-80801\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019179.jpg 1572w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019179-300x199.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019179-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019179-768x509.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019179-1536x1017.jpg 1536w\" sizes=\"(max-width: 1572px) 100vw, 1572px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1572\" height=\"1041\" data-id=\"80802\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019183.jpg\" alt=\"\" class=\"wp-image-80802\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019183.jpg 1572w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019183-300x199.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019183-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019183-768x509.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019183-1536x1017.jpg 1536w\" sizes=\"(max-width: 1572px) 100vw, 1572px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1572\" height=\"1041\" data-id=\"80803\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019185.jpg\" alt=\"\" class=\"wp-image-80803\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019185.jpg 1572w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019185-300x199.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019185-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019185-768x509.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019185-1536x1017.jpg 1536w\" sizes=\"(max-width: 1572px) 100vw, 1572px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1572\" height=\"1041\" data-id=\"80804\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019184.jpg\" alt=\"\" class=\"wp-image-80804\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019184.jpg 1572w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019184-300x199.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019184-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019184-768x509.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019184-1536x1017.jpg 1536w\" sizes=\"(max-width: 1572px) 100vw, 1572px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1572\" height=\"1041\" data-id=\"80805\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019188.jpg\" alt=\"\" class=\"wp-image-80805\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019188.jpg 1572w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019188-300x199.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019188-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019188-768x509.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019188-1536x1017.jpg 1536w\" sizes=\"(max-width: 1572px) 100vw, 1572px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1572\" height=\"1041\" data-id=\"80806\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019187.jpg\" alt=\"\" class=\"wp-image-80806\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019187.jpg 1572w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019187-300x199.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019187-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019187-768x509.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019187-1536x1017.jpg 1536w\" sizes=\"(max-width: 1572px) 100vw, 1572px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1654\" height=\"990\" data-id=\"80807\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019186.jpg\" alt=\"\" class=\"wp-image-80807\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019186.jpg 1654w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019186-300x180.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019186-50x30.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019186-768x460.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019186-1536x919.jpg 1536w\" sizes=\"(max-width: 1654px) 100vw, 1654px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1572\" height=\"1041\" data-id=\"80808\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019189.jpg\" alt=\"\" class=\"wp-image-80808\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019189.jpg 1572w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019189-300x199.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019189-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019189-768x509.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019189-1536x1017.jpg 1536w\" sizes=\"(max-width: 1572px) 100vw, 1572px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1570\" height=\"1042\" data-id=\"80809\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019180.jpg\" alt=\"\" class=\"wp-image-80809\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019180.jpg 1570w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019180-300x199.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019180-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019180-768x510.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019180-1536x1019.jpg 1536w\" sizes=\"(max-width: 1570px) 100vw, 1570px\" \/><\/figure>\n<\/figure>\n\r\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 11 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2567 \u0e14\u0e23.\u0e20\u0e31\u0e2a\u0e0a\u0e0d\u0e20\u0e13 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e41\u0e08\u0e49\u0e07 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":80798,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-80797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news_board"],"uagb_featured_image_src":{"full":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019178.jpg",1473,1112,false],"thumbnail":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019178-50x38.jpg",50,38,true],"medium":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019178-300x226.jpg",300,226,true],"medium_large":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019178-768x580.jpg",750,566,true],"large":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019178.jpg",1473,1112,false],"1536x1536":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019178.jpg",1473,1112,false],"2048x2048":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/09\/1000019178.jpg",1473,1112,false]},"uagb_author_info":{"display_name":"\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23","author_link":"https:\/\/www.doa.go.th\/th\/author\/webmass\/"},"uagb_comment_info":0,"uagb_excerpt":"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 11 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2567 \u0e14\u0e23.\u0e20\u0e31\u0e2a\u0e0a\u0e0d\u0e20\u0e13 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e41\u0e08\u0e49\u0e07 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34&hellip;","acf":[],"_links":{"self":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts\/80797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/comments?post=80797"}],"version-history":[{"count":1,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts\/80797\/revisions"}],"predecessor-version":[{"id":80810,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts\/80797\/revisions\/80810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/media\/80798"}],"wp:attachment":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/media?parent=80797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/categories?post=80797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/tags?post=80797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}