{"id":81921,"date":"2024-10-02T18:43:00","date_gmt":"2024-10-02T11:43:00","guid":{"rendered":"https:\/\/www.doa.go.th\/th\/?p=81921"},"modified":"2024-10-03T08:47:28","modified_gmt":"2024-10-03T01:47:28","slug":"%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%b7%e0%b8%ad%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87","status":"publish","type":"post","link":"https:\/\/www.doa.go.th\/th\/news_board\/81921\/","title":{"rendered":"\u0e01\u0e32\u0e23\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30 RSPO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 2 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2567 \u0e19\u0e32\u0e22\u0e16\u0e32\u0e27\u0e23 \u0e17\u0e31\u0e19\u0e43\u0e08 \u0e1c\u0e39\u0e49\u0e15\u0e23\u0e27\u0e08\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c \u0e44\u0e14\u0e49\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e19\u0e32\u0e22 \u0e42\u0e08\u0e40\u0e0b\u0e1f \u0e40\u0e14\u0e2d \u0e04\u0e23\u0e39\u0e0b (Mr. Joseph D\u2019Cruz) \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e02\u0e2d\u0e07 Roundtable on Sustainable Palm Oil (RSPO) \u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49\u0e19\u0e32\u0e22\u0e23\u0e1e\u0e35\u0e20\u0e31\u0e17\u0e23\u0e4c \u0e08\u0e31\u0e19\u0e17\u0e23\u0e28\u0e23\u0e35\u0e27\u0e07\u0e28\u0e4c \u0e2d\u0e18\u0e34\u0e1a\u0e14\u0e35\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c 112<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30 RSPO \u0e43\u0e19\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 RSPO \u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e42\u0e14\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 RSPO \u0e08\u0e30\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e15\u0e32\u0e21\u0e01\u0e0e\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49\u0e2d\u0e18\u0e34\u0e1a\u0e14\u0e35\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e04\u0e13\u0e30\u0e08\u0e32\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 RSPO \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19 \u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2f \u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 RSPO \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15 \u0e43\u0e19\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e34\u0e15\u0e23\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 RSPO \u0e04\u0e27\u0e1a\u0e04\u0e39\u0e48\u0e44\u0e1b\u0e01\u0e31\u0e1a\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e1c\u0e39\u0e49\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19 VVB \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e32\u0e22\u0e22\u0e48\u0e2d\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15\u0e43\u0e19\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 RSPO \u0e44\u0e14\u0e49\u0e40\u0e0a\u0e34\u0e0d\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2024 (RT2024) \u0e43\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2567 \u0e13 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 Amari Bangkok \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u0e0b\u0e36\u0e48\u0e07\u0e07\u0e32\u0e19\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e27\u0e34\u0e2a\u0e31\u0e22\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e43\u0e19\u0e2d\u0e35\u0e01 20 \u0e1b\u0e35\u0e02\u0e49\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e42\u0e14\u0e22\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2f \u0e22\u0e34\u0e19\u0e14\u0e35\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e15\u0e48\u0e2d\u0e44\u0e1b<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1568\" height=\"1044\" data-id=\"81923\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781001_0.jpg\" alt=\"\" class=\"wp-image-81923\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781001_0.jpg 1568w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781001_0-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781001_0-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781001_0-768x511.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781001_0-1536x1023.jpg 1536w\" sizes=\"(max-width: 1568px) 100vw, 1568px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1568\" height=\"1044\" data-id=\"81922\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781002_0.jpg\" alt=\"\" class=\"wp-image-81922\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781002_0.jpg 1568w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781002_0-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781002_0-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781002_0-768x511.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781002_0-1536x1023.jpg 1536w\" sizes=\"(max-width: 1568px) 100vw, 1568px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1568\" height=\"1044\" data-id=\"81925\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781003_0.jpg\" alt=\"\" class=\"wp-image-81925\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781003_0.jpg 1568w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781003_0-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781003_0-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781003_0-768x511.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781003_0-1536x1023.jpg 1536w\" sizes=\"(max-width: 1568px) 100vw, 1568px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1568\" height=\"1044\" data-id=\"81927\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781006_0.jpg\" alt=\"\" class=\"wp-image-81927\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781006_0.jpg 1568w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781006_0-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781006_0-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781006_0-768x511.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781006_0-1536x1023.jpg 1536w\" sizes=\"(max-width: 1568px) 100vw, 1568px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1568\" height=\"1044\" data-id=\"81926\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781005_0.jpg\" alt=\"\" class=\"wp-image-81926\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781005_0.jpg 1568w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781005_0-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781005_0-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781005_0-768x511.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781005_0-1536x1023.jpg 1536w\" sizes=\"(max-width: 1568px) 100vw, 1568px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1568\" height=\"1044\" data-id=\"81924\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781004_0.jpg\" alt=\"\" class=\"wp-image-81924\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781004_0.jpg 1568w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781004_0-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781004_0-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781004_0-768x511.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781004_0-1536x1023.jpg 1536w\" sizes=\"(max-width: 1568px) 100vw, 1568px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1568\" height=\"1044\" data-id=\"81928\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781007_0.jpg\" alt=\"\" class=\"wp-image-81928\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781007_0.jpg 1568w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781007_0-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781007_0-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781007_0-768x511.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781007_0-1536x1023.jpg 1536w\" sizes=\"(max-width: 1568px) 100vw, 1568px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1568\" height=\"1044\" data-id=\"81929\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781008_0.jpg\" alt=\"\" class=\"wp-image-81929\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781008_0.jpg 1568w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781008_0-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781008_0-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781008_0-768x511.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781008_0-1536x1023.jpg 1536w\" sizes=\"(max-width: 1568px) 100vw, 1568px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1568\" height=\"1044\" data-id=\"81930\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781009_0.jpg\" alt=\"\" class=\"wp-image-81930\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781009_0.jpg 1568w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781009_0-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781009_0-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781009_0-768x511.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781009_0-1536x1023.jpg 1536w\" sizes=\"(max-width: 1568px) 100vw, 1568px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1568\" height=\"1044\" data-id=\"81934\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781013_0.jpg\" alt=\"\" class=\"wp-image-81934\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781013_0.jpg 1568w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781013_0-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781013_0-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781013_0-768x511.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781013_0-1536x1023.jpg 1536w\" sizes=\"(max-width: 1568px) 100vw, 1568px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1568\" height=\"1044\" data-id=\"81931\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781010_0.jpg\" alt=\"\" class=\"wp-image-81931\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781010_0.jpg 1568w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781010_0-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781010_0-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781010_0-768x511.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781010_0-1536x1023.jpg 1536w\" sizes=\"(max-width: 1568px) 100vw, 1568px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1568\" height=\"1044\" data-id=\"81935\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781014_0.jpg\" alt=\"\" class=\"wp-image-81935\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781014_0.jpg 1568w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781014_0-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781014_0-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781014_0-768x511.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781014_0-1536x1023.jpg 1536w\" sizes=\"(max-width: 1568px) 100vw, 1568px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1568\" height=\"1044\" data-id=\"81932\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781011_0.jpg\" alt=\"\" class=\"wp-image-81932\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781011_0.jpg 1568w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781011_0-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781011_0-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781011_0-768x511.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781011_0-1536x1023.jpg 1536w\" sizes=\"(max-width: 1568px) 100vw, 1568px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1568\" height=\"1044\" data-id=\"81933\" src=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781012_0.jpg\" alt=\"\" class=\"wp-image-81933\" srcset=\"https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781012_0.jpg 1568w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781012_0-300x200.jpg 300w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781012_0-50x33.jpg 50w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781012_0-768x511.jpg 768w, https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781012_0-1536x1023.jpg 1536w\" sizes=\"(max-width: 1568px) 100vw, 1568px\" \/><\/figure>\n<\/figure>\n\r\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 2 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2567 \u0e19\u0e32\u0e22\u0e16\u0e32\u0e27\u0e23 \u0e17\u0e31\u0e19\u0e43\u0e08 \u0e1c\u0e39\u0e49\u0e15\u0e23\u0e27\u0e08\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81932,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-81921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news_board"],"uagb_featured_image_src":{"full":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781011_0.jpg",1568,1044,false],"thumbnail":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781011_0-50x33.jpg",50,33,true],"medium":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781011_0-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781011_0-768x511.jpg",750,499,true],"large":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781011_0.jpg",1568,1044,false],"1536x1536":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781011_0-1536x1023.jpg",1536,1023,true],"2048x2048":["https:\/\/www.doa.go.th\/th\/wp-content\/uploads\/2024\/10\/781011_0.jpg",1568,1044,false]},"uagb_author_info":{"display_name":"\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23","author_link":"https:\/\/www.doa.go.th\/th\/author\/webmass\/"},"uagb_comment_info":0,"uagb_excerpt":"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 2 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2567 \u0e19\u0e32\u0e22\u0e16\u0e32\u0e27\u0e23 \u0e17\u0e31\u0e19\u0e43\u0e08 \u0e1c\u0e39\u0e49\u0e15\u0e23\u0e27\u0e08\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23&hellip;","acf":[],"_links":{"self":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts\/81921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/comments?post=81921"}],"version-history":[{"count":3,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts\/81921\/revisions"}],"predecessor-version":[{"id":81938,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/posts\/81921\/revisions\/81938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/media\/81932"}],"wp:attachment":[{"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/media?parent=81921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/categories?post=81921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doa.go.th\/th\/wp-json\/wp\/v2\/tags?post=81921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}